{"id":535,"count":47,"description":"<h2><b><span data-contrast=\"auto\">Chaises design pour les h\u00f4tels <\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\r\n<span data-contrast=\"auto\">Les chaises design sont un excellent moyen de revitaliser les espaces communs des h\u00f4tels et des bureaux. Avec des designs originaux et contemporains, chez Contract Solutions, nous vous proposons des chaises rembourr\u00e9es vintage, des chaises en bois modernes, ainsi que des chaises amusantes en polypropyl\u00e8ne de couleur ou transparentes.\u00a0\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>\r\n\r\n<span data-contrast=\"auto\">Dans notre vaste catalogue de chaises, vous trouverez les mod\u00e8les parfaits pour chaque pi\u00e8ce. Si vous recherchez des chaises pour des salons spacieux, jetez un \u0153il \u00e0 des mod\u00e8les tels que la chaise Feston ou la chaise rembourr\u00e9e Brent. Ou si vous pr\u00e9f\u00e9rez, achetez des mod\u00e8les tels que la chaise Bombom ou la chaise Moabi, dont le design vintage apporte chaleur et bien-\u00eatre aux pi\u00e8ces. Une grande s\u00e9lection des cr\u00e9ations les plus personnelles pour rendre les espaces des h\u00f4tels, des restaurants et des bureaux accueillants et confortables pour les clients qui les visitent.\u00a0\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>\r\n\r\n<span data-ccp-props=\"{}\">\u00a0<\/span>\r\n<h2><b><span data-contrast=\"auto\">Chaises r\u00e9sistantes pour l'h\u00f4tellerie et la restauration <\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\r\n<span data-contrast=\"auto\">Nous disposons \u00e9galement des meilleures chaises robustes pour le secteur de l'h\u00f4tellerie et de la restauration, notamment des chaises pliantes en prilopropyl\u00e8ne et des chaises en technopolym\u00e8re, adapt\u00e9es \u00e0 un d\u00e9cor int\u00e9rieur et ext\u00e9rieur. Nous avons m\u00eame des chaises pour enfants design, comme la chaise Snow Kids, avec laquelle vous pouvez d\u00e9corer les chambres et les pi\u00e8ces con\u00e7ues pour les petits. N'h\u00e9sitez pas non plus \u00e0 jeter un coup d'\u0153il \u00e0 nos chaises design originales, id\u00e9ales pour donner cette touche \u00e9clectique que certaines entreprises recherchent dans leurs installations. <\/span><span data-contrast=\"auto\">Vous pouvez y parvenir avec des mod\u00e8les tels que la chaise Remind, de Pedrali, ou la chaise Swan, con\u00e7ue par Arne Jacobsen pour le SAS Royal Hotel de Copenhague.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>","link":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/","name":"Chaises contractuelles","slug":"chaises-contractuelles","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chaises design | Chaises Modernes | Soluciones Contract<\/title>\n<meta name=\"description\" content=\"Cr\u00e9ez des environnements exclusifs avec les chaises design de Soluciones Contract. Achetez des chaises modernes en ligne pour les caf\u00e9s, les h\u00f4tels et les particuliers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaises design | Chaises Modernes | Soluciones Contract\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9ez des environnements exclusifs avec les chaises design de Soluciones Contract. Achetez des chaises modernes en ligne pour les caf\u00e9s, les h\u00f4tels et les particuliers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Soluciones Contract\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/fr\\\/categoria-producto\\\/chaises-contractuelles\\\/\",\"url\":\"https:\\\/\\\/solucionescontract.com\\\/fr\\\/categoria-producto\\\/chaises-contractuelles\\\/\",\"name\":\"Chaises design | Chaises Modernes | Soluciones Contract\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/#website\"},\"description\":\"Cr\u00e9ez des environnements exclusifs avec les chaises design de Soluciones Contract. Achetez des chaises modernes en ligne pour les caf\u00e9s, les h\u00f4tels et les particuliers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/fr\\\/categoria-producto\\\/chaises-contractuelles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/fr\\\/categoria-producto\\\/chaises-contractuelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/solucionescontract.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda mobiliario contract\",\"item\":\"https:\\\/\\\/solucionescontract.com\\\/tienda-mobiliario-contract\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chaises contractuelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/#website\",\"url\":\"https:\\\/\\\/solucionescontract.com\\\/\",\"name\":\"Soluciones Contract\",\"description\":\"Venta Mobiliario contract de dise\u00f1o\",\"publisher\":{\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solucionescontract.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/#organization\",\"name\":\"Soluciones Contract\",\"url\":\"https:\\\/\\\/solucionescontract.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solucionescontract.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logoSC.jpg\",\"contentUrl\":\"https:\\\/\\\/solucionescontract.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logoSC.jpg\",\"width\":300,\"height\":125,\"caption\":\"Soluciones Contract\"},\"image\":{\"@id\":\"https:\\\/\\\/solucionescontract.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solucionescontract\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaises design | Chaises Modernes | Soluciones Contract","description":"Cr\u00e9ez des environnements exclusifs avec les chaises design de Soluciones Contract. Achetez des chaises modernes en ligne pour les caf\u00e9s, les h\u00f4tels et les particuliers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Chaises design | Chaises Modernes | Soluciones Contract","og_description":"Cr\u00e9ez des environnements exclusifs avec les chaises design de Soluciones Contract. Achetez des chaises modernes en ligne pour les caf\u00e9s, les h\u00f4tels et les particuliers.","og_url":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/","og_site_name":"Soluciones Contract","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/","url":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/","name":"Chaises design | Chaises Modernes | Soluciones Contract","isPartOf":{"@id":"https:\/\/solucionescontract.com\/#website"},"description":"Cr\u00e9ez des environnements exclusifs avec les chaises design de Soluciones Contract. Achetez des chaises modernes en ligne pour les caf\u00e9s, les h\u00f4tels et les particuliers.","breadcrumb":{"@id":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/solucionescontract.com\/fr\/categoria-producto\/chaises-contractuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/solucionescontract.com\/"},{"@type":"ListItem","position":2,"name":"Tienda mobiliario contract","item":"https:\/\/solucionescontract.com\/tienda-mobiliario-contract\/"},{"@type":"ListItem","position":3,"name":"Chaises contractuelles"}]},{"@type":"WebSite","@id":"https:\/\/solucionescontract.com\/#website","url":"https:\/\/solucionescontract.com\/","name":"Soluciones Contract","description":"Venta Mobiliario contract de dise\u00f1o","publisher":{"@id":"https:\/\/solucionescontract.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solucionescontract.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/solucionescontract.com\/#organization","name":"Soluciones Contract","url":"https:\/\/solucionescontract.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solucionescontract.com\/#\/schema\/logo\/image\/","url":"https:\/\/solucionescontract.com\/wp-content\/uploads\/2020\/02\/logoSC.jpg","contentUrl":"https:\/\/solucionescontract.com\/wp-content\/uploads\/2020\/02\/logoSC.jpg","width":300,"height":125,"caption":"Soluciones Contract"},"image":{"@id":"https:\/\/solucionescontract.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solucionescontract\/"]}]}},"_links":{"self":[{"href":"https:\/\/solucionescontract.com\/fr\/wp-json\/wp\/v2\/product_cat\/535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solucionescontract.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/solucionescontract.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/solucionescontract.com\/fr\/wp-json\/wp\/v2\/product?product_cat=535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}